{"id":3243,"date":"2016-07-24T13:53:18","date_gmt":"2016-07-24T13:53:18","guid":{"rendered":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/open-48\/"},"modified":"2020-07-27T10:01:20","modified_gmt":"2020-07-27T10:01:20","slug":"concours-aventures-famille","status":"publish","type":"post","link":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/","title":{"rendered":"Racontez-nous vos aventures en famille et gagnez des bons d&rsquo;achat dans la boutique"},"content":{"rendered":"<p style=\"text-align: justify;\">Un coup de coeur nature ? Une <strong>rando<\/strong> favorite ? Un <strong>voyage<\/strong> de folie ? Une <strong>activit\u00e9<\/strong> insolite \u00a0?<!--more--><\/p>\n<h2 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1190\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2016\/07\/visuel-article-blog2.jpg\" alt=\"Concours &quot;Racontez vos aventures en famille&quot;\" width=\"700\" height=\"150\" \/><\/h2>\n<h2 style=\"text-align: justify;\">Racontez-nous vos sorties nature en famille !<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nous vous invitons cet \u00e9t\u00e9 \u00e0 <strong>partager le r\u00e9cit de vos aventures natures v\u00e9cues avec vos petits baroudeurs<\/strong>. Les sites de voyage c\u2019est chouette, mais rien ne vaut le retour d\u2019exp\u00e9rience et le partage de r\u00e9cits des familles \u00e0 l\u2019arriv\u00e9e de leurs aventures. C\u2019est pour cela que nous vous proposons un <strong>jeu concours estival<\/strong> qui vous donnera l\u2019occasion de <strong>partager vos conseils<\/strong> aupr\u00e8s d\u2019une communaut\u00e9 de parents avide de nouvelles id\u00e9es ! <\/span><\/p>\n<p style=\"text-align: justify;\"><strong>A la cl\u00e9, des bons d\u2019achat \u00e0 gagner sur la boutique Les petits baroudeurs avouez que l&rsquo;on vous soigne \ud83d\ude09<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Vos aventures seront <strong>publi\u00e9es sur notre blog<\/strong> vous aurez ainsi l&rsquo;honneur de les partager avec le reste de la communaut\u00e9 des Petits Baroudeurs et, mieux encore, d&rsquo;aider des familles \u00e0 franchir le pas de partir en balade avec leurs petits aventuriers.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><strong>Toutes les exp\u00e9riences sont bonnes \u00e0 prendre<\/strong> alors pas de limite pour vos topos il pourra donc s\u2019agir d\u2019activit\u00e9s natures classiques, balade en poney, rando, vtt, accrobranche ou de voyages en France ou \u00e0 l\u2019\u00e9tranger, ou d\u2019autres d\u00e9couvertes comme les fermes p\u00e9dagogiques, les parcours enfants nature&#8230;<\/span><\/p>\n<h2 style=\"text-align: justify;\">Le d\u00e9roulement du jeu<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Vous avez jusqu\u2019au <span style=\"text-decoration: underline;\"><strong>15 Septembre<\/strong><\/span> pour remplir le formulaire\u00a0que nous vous avons pr\u00e9par\u00e9 et nous l\u2019envoyer accompagn\u00e9 de quelques photos pour illustrer les r\u00e9cits.<\/span><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s une petite s\u00e9lection des coups de coeur de la famille ours, vos r\u00e9cits d\u2019aventure seront publi\u00e9s sur le blog.\u00a0<span style=\"text-decoration: underline;\"><strong>Du 15 au 30 septembre, ce sera \u00e0 vous de faire voter vos amis<\/strong><\/span> pour obtenir le plus de \u00ab\u00a0j&rsquo;aime\u00a0\u00bb sur votre r\u00e9cit. Les 3 r\u00e9cits comptabilisant le plus de \u00ab\u00a0like\u00a0\u00bb seront les gagnants.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><strong>D\u00e8s le 5 Octobre nous annoncerons le palmar\u00e8s final\u00a0!<\/strong><\/span><\/p>\n<h2 style=\"text-align: justify;\">Les cadeaux \u00e0 gagner<\/h2>\n<ul>\n<li style=\"text-align: justify;\">\n<blockquote><p><span style=\"font-weight: 400;\">1er prix : un bon d\u2019achat d&rsquo;une valeur de 75\u20ac<\/span><\/p><\/blockquote>\n<\/li>\n<li style=\"text-align: justify;\">\n<blockquote><p><span style=\"font-weight: 400;\">2\u00e8me prix :un bon d\u2019achat d&rsquo;une valeur de 30\u20ac<\/span><\/p><\/blockquote>\n<\/li>\n<li style=\"text-align: justify;\">\n<blockquote><p><span style=\"font-weight: 400;\">3\u00e8me prix :un bon d\u2019achat d&rsquo;une valeur de 20\u20ac<\/span><\/p><\/blockquote>\n<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">C\u2019est parti : pour jouer c&rsquo;est ici !<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Remplissez le formulaire\u00a0et <a href=\"http:\/\/bit.ly\/29H6j8P\" target=\"_blank\" rel=\"noopener noreferrer\">racontez-nous vos exp\u00e9riences ici<\/a>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A la suite de votre r\u00e9daction, envoyez-nous vos photos (les instructions se trouvent dans le formulaire). <\/span><\/p>\n<h2 style=\"text-align: justify;\">Le r\u00e9cap\u2019 du jeu en image<\/h2>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1187\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2016\/07\/guide-concours-recapfinal.jpg\" alt=\"Concours &quot;Racontez vos aventures en famille&quot;\" width=\"700\" height=\"600\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A vos claviers !<br \/>\nEt si vous avez la moindre question, n&rsquo;h\u00e9sitez pas \u00e0 nous contacter \u00e0 contact[@]lespetitsbaroudeurs.com<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un coup de coeur nature ? Une rando favorite ? Un voyage de folie ? Une activit\u00e9 insolite \u00a0?<\/p>\n","protected":false},"author":36,"featured_media":3244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[142],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Racontez-nous vos aventures en famille et gagnez des bons d&#039;achat dans la boutique - Les Petits Baroudeurs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Racontez-nous vos aventures en famille et gagnez des bons d&#039;achat dans la boutique - Les Petits Baroudeurs\" \/>\n<meta property=\"og:description\" content=\"Un coup de coeur nature ? Une rando favorite ? Un voyage de folie ? Une activit\u00e9 insolite \u00a0?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Petits Baroudeurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lespetitsbaroudeurs\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-24T13:53:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-27T10:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2020\/07\/visuel-article-blog1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#website\",\"url\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/\",\"name\":\"Les Petits Baroudeurs\",\"description\":\"Le Blog de l&#039;aventure en famille !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2020\/07\/visuel-article-blog1.jpg\",\"width\":700,\"height\":500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/#webpage\",\"url\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/\",\"name\":\"Racontez-nous vos aventures en famille et gagnez des bons d'achat dans la boutique - Les Petits Baroudeurs\",\"isPartOf\":{\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/#primaryimage\"},\"author\":{\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#\/schema\/person\/074061ec8b5473878afb9cce3c002d69\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/concours-aventures-famille\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#\/schema\/person\/074061ec8b5473878afb9cce3c002d69\",\"name\":\"C\\u00e9line Lacombe\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3196c6923379068e921575c340f8486?s=96&d=mm&r=g\",\"caption\":\"C\\u00e9line Lacombe\"},\"description\":\"Amoureuse des montagnes et des voyages, C\\u00e9line est heureuse dans sa tribu familiale avec ses mini baroudeurs et son homme. La cr\\u00e9ation des Petits Baroudeurs est la suite logique de sa passion pour sa famille et pour l'outdoor.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts\/3243"}],"collection":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/comments?post=3243"}],"version-history":[{"count":1,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts\/3243\/revisions"}],"predecessor-version":[{"id":4299,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts\/3243\/revisions\/4299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/media\/3244"}],"wp:attachment":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/media?parent=3243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/categories?post=3243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/tags?post=3243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}