{"id":6636,"date":"2021-06-23T11:46:57","date_gmt":"2021-06-23T09:46:57","guid":{"rendered":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/?p=6636"},"modified":"2021-07-23T10:04:43","modified_gmt":"2021-07-23T08:04:43","slug":"nos-conseils-pour-preparer-un-voyage-a-velo-en-famille","status":"publish","type":"post","link":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/","title":{"rendered":"Nos conseils pour pr\u00e9parer un voyage \u00e0 v\u00e9lo en famille"},"content":{"rendered":"\n<p><strong>Vous avez envie de vous lancer dans un premier voyage \u00e0 v\u00e9lo en famille mais vous vous posez encore mille et une questions ? D\u00e9couvrez tous nos conseils pour pr\u00e9parer au mieux votre voyage et partez p\u00e9daler avec vos enfants !<\/strong><\/p>\n\n\n\n<h2>Organiser son voyage \u00e0 v\u00e9lo en famille<\/h2>\n\n\n\n<p>Avant toute chose, il faut savoir qu\u2019il est tout \u00e0 fait possible <strong>de partir \u00e0 v\u00e9lo avec des enfants<\/strong>, m\u00eame s\u2019ils sont jeunes ! La famille n\u2019est pas une contrainte en elle-m\u00eame, ni l\u2019\u00e2ge et le nombre d\u2019enfants, cela <strong>n\u00e9cessitera<\/strong> <strong>juste un peu d\u2019organisation<\/strong>. Comme toujours en voyage, les enfants <strong>facilitent les \u00e9changes avec les autres<\/strong>, ce qui est aussi valable pour une <strong>aventure \u00e0 v\u00e9lo en famille<\/strong> ! C\u2019est une tr\u00e8s bonne occasion de leur faire d\u00e9couvrir le patrimoine culturel dont regorge notre beau pays, mais \u00e9galement la <strong>faune et la flore <\/strong>qui nous entourent. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4596.jpg\" alt=\"voyage-a-velo-en-famille-organisation\" class=\"wp-image-5964\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4596.jpg 1024w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4596-300x200.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4596-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En plus, le voyage \u00e0 v\u00e9lo a un <strong>impact limit\u00e9 sur l\u2019environnement<\/strong> : un bon moyen de sensibiliser les marmots et de leur montrer <strong>les bons gestes pour prot\u00e9ger la nature<\/strong>. Quoi de mieux pour les ouvrir sur le monde qui nous entoure que de passer plusieurs heures \u00e0 <strong>p\u00e9daler au grand air<\/strong> ? Si on aime partir \u00e0 l\u2019aventure, le v\u00e9lo est id\u00e9al, alors m\u00eame qu\u2019on ne peut pas tout porter comme en rando.&nbsp;<\/p>\n\n\n\n<p>Et si on veut <strong>s\u2019inspirer et se rassurer<\/strong>, un bon moyen de le faire est de partir \u00e0 la recherche <strong>d\u2019informations et de r\u00e9cits d\u2019autres familles<\/strong> ayant d\u00e9j\u00e0 tent\u00e9 l\u2019aventure. Enfin, <strong>associez les enfants \u00e0 la pr\u00e9paration du voyage<\/strong> et ils seront tout excit\u00e9s d\u2019y prendre part !<\/p>\n\n\n\n<h3>Combien de temps partir ? <\/h3>\n\n\n\n<p>\u00c9videmment, <strong>si on est d\u00e9butant<\/strong>, il vaut mieux y aller petit \u00e0 petit et <strong>pr\u00e9voir une itin\u00e9rance de quelques jours seulement<\/strong>, plut\u00f4t proche de chez nous. Cela permettra de voir si l\u2019aventure pla\u00eet \u00e0 tout le monde, avant de se lancer dans <strong>un plus grand voyage \u00e0 v\u00e9lo en famille<\/strong> ! Et en plus, vous pourrez facilement vous rendre compte du poids de l\u2019\u00e9quipement, mais aussi <strong>du nombre de kilom\u00e8tres<\/strong> qu\u2019il est possible de faire avec des enfants, et <strong>ajuster les derniers \u00e9l\u00e9ments avant le voyage.<\/strong><\/p>\n\n\n\n<h3>A quelle p\u00e9riode partir ?<\/h3>\n\n\n\n<p>Concr\u00e8tement, m\u00eame si on peut partir n\u2019importe quand, l\u2019id\u00e9al reste quand m\u00eame <strong>d\u2019attendre les&nbsp;beaux jours <\/strong>car la m\u00e9t\u00e9o sera plus cl\u00e9mente. Cela signifie <strong>moins de v\u00eatements \u00e0 pr\u00e9voir<\/strong>, et plus de chances de p\u00e9daler au sec ! Votre budget est \u00e9galement un \u00e9l\u00e9ment \u00e0 prendre en compte, car si vous n\u2019avez pas pr\u00e9vu de camper, mais de dormir dans des h\u00e9bergements \u201cen dur\u201d, les prix peuvent <strong>vite grimper en pleine saison.<\/strong><\/p>\n\n\n\n<h3>Bien choisir son itin\u00e9raire v\u00e9lo<\/h3>\n\n\n\n<p>Que vous partiez deux jours ou une semaine, <strong>le choix de l\u2019itin\u00e9raire<\/strong> est un \u00e9l\u00e9ment important dans <strong>l\u2019organisation de votre voyage \u00e0 v\u00e9lo en famille<\/strong>. S\u2019il s\u2019agit de votre premi\u00e8re aventure, ou que vos marmots sont petits, il vaut mieux <strong>privil\u00e9gier les voies vertes et les parcours faciles<\/strong>, si possible sans circulation. Il existe notamment <strong>des itin\u00e9raires cyclables s\u00e9curis\u00e9s<\/strong> le long des canaux ou sur d\u2019anciennes voies ferr\u00e9es, qui sont id\u00e9aux pour d\u00e9buter. L\u2019essentiel est de <strong>choisir un circuit adapt\u00e9 aux capacit\u00e9s de chacun<\/strong>, surtout si on p\u00e9dale avec de jeunes enfants. Un conseil, <strong>commencez par des \u00e9tapes un peu plus courtes<\/strong>, cela permet de se mettre dans le bain !&nbsp;<br>Il existe plusieurs moyens de<strong> tracer son itin\u00e9raire \u00e0 v\u00e9lo<\/strong> :<\/p>\n\n\n\n<ul><li><strong>Utiliser Google Maps<\/strong> en se mettant \u201cen mode v\u00e9lo\u201d, pour rep\u00e9rer les diff\u00e9rentes <strong>pistes cyclables et voies vertes<\/strong>.&nbsp;<\/li><li>Aller sur le site de <a rel=\"noreferrer noopener\" href=\"https:\/\/www.francevelotourisme.com\/\" target=\"_blank\">France V\u00e9lo Tourisme<\/a> et <strong>ajouter chaque \u00e9tape<\/strong> du trajet qu\u2019on a pr\u00e9vu.<\/li><\/ul>\n\n\n\n<p>En p\u00e9dalant, vous allez s\u00fbrement croiser la route d\u2019un ch\u00e2teau, d\u2019un parc&#8230;Profitez-en pour vous y arr\u00eater ! Cela permettra de <strong>faire des haltes et de vous reposer<\/strong>, mais aussi de <strong>d\u00e9gourdir les jambes<\/strong> des loupiots qui se trouveraient dans une remorque ou un si\u00e8ge v\u00e9lo. Il est \u00e9galement possible de <strong>pr\u00e9voir l\u2019itin\u00e9raire de son voyage \u00e0 v\u00e9lo en famille<\/strong> en fonction des lieux qu\u2019on aura rep\u00e9r\u00e9s pour dormir, selon les distances \u00e0 parcourir entre chaque \u00e9tape.<\/p>\n\n\n\n<p>D\u00e9couvrez quelques-unes de <strong>nos itin\u00e9rances favorites \u00e0 v\u00e9lo<\/strong>, test\u00e9es et approuv\u00e9es par nos familles ambassadrices, ou par nous m\u00eames, la famille Ours :<\/p>\n\n\n\n<ul><li>La <a href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/la-dolce-via-en-famille-a-velo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dolce Via<\/a><\/li><li>La <a href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/bicyclette-en-famille-sur-la-velo-francette-sur-les-bords-de-la-mayenne-de-laval-a-angers\/\" target=\"_blank\" rel=\"noreferrer noopener\">V\u00e9lo Francette<\/a><\/li><li>La <a href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/la-velodyssee-en-famille-a-travers-la-bretagne-et-le-long-de-latlantique\/\" target=\"_blank\" rel=\"noreferrer noopener\">V\u00e9lodyss\u00e9e<\/a><\/li><li><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/belle-ile-en-mer-a-velo-en-famille\/\" target=\"_blank\" rel=\"noreferrer noopener\">Belle Ile en Mer \u00e0 v\u00e9lo<\/a><\/li><li>Le <a href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/vacances-velo-en-famille-tarn\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tarn \u00e0 v\u00e9lo<\/a> en famille<\/li><li>Le <a href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/velo-famille-toulouse-hossegor\/\" target=\"_blank\" rel=\"noreferrer noopener\">Canal des Deux Mers : de Toulouse \u00e0 Hossegor<\/a><\/li><\/ul>\n\n\n\n<h3>Choisir son type de couchage<\/h3>\n\n\n\n<p>Partir sur plusieurs jours implique de devoir <strong>choisir un ou plusieurs moyens d&rsquo;h\u00e9bergement<\/strong> pour la nuit. Diff\u00e9rentes solutions s\u2019offrent alors \u00e0 vous, et le choix d\u00e9pendra de vos habitudes, de vos envies, mais aussi de la dur\u00e9e de votre aventure \u00e0 v\u00e9lo, et de la saison.<\/p>\n\n\n\n<h4>Faire du bivouac<\/h4>\n\n\n\n<p>Si on est <strong>adepte du bivouac<\/strong>, on peut tout \u00e0 fait <strong>associer nuit sous la tente et itin\u00e9rance \u00e0 v\u00e9lo<\/strong> ! Mais attention, cela fait tout de m\u00eame bien plus de mat\u00e9riel \u00e0 transporter, et demande un peu d\u2019organisation. L\u00e0 encore, cela <strong>d\u00e9pendra de l\u2019\u00e2ge des loupiots<\/strong>, mais aussi de la <strong>p\u00e9riode \u00e0 laquelle on a pr\u00e9vu de partir<\/strong>. Camper pendant son voyage \u00e0 v\u00e9lo en famille comporte tout de m\u00eame certains avantages : on n\u2019est pas enferm\u00e9 dans une chambre, les enfants se font vite des copains\u2026 et \u00e7a donne <strong>un petit c\u00f4t\u00e9 aventure<\/strong> ! Privil\u00e9gier <strong>les petits campings familiaux<\/strong> permettra d\u2019\u00eatre plus tranquille et d\u2019avoir plus de chances de trouver un emplacement de derni\u00e8re minute. Et puis, les enfants <strong>pourront courir partout<\/strong> pendant que les plus grands installent le campement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4057.jpg\" alt=\"voyage-a-velo-en-famille-bivouac\" class=\"wp-image-5957\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4057.jpg 1024w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4057-300x200.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/IMG_4057-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Bivouaquer pendant une itin\u00e9rance \u00e0 v\u00e9lo<\/figcaption><\/figure>\n\n\n\n<p>Nous on adore dormir dans les <strong>\u201cpr\u00eats \u00e0 camper\u201d<\/strong>, car ils rassemblent <strong>tous les avantages du camping<\/strong>. Ils nous permettent d\u2019\u00eatre dehors et de faire notre nourriture, mais <strong>en ayant tout le n\u00e9cessaire fourni<\/strong> : les draps, la tente, de quoi cuisiner&#8230;Ils existent sous forme de mobil-homes, mais ce qu\u2019on pr\u00e9f\u00e8re, c\u2019est carr\u00e9ment <strong>les tentes trappeurs<\/strong>, qui nous font nous sentir comme des aventuriers !<\/p>\n\n\n\n<h4>Aller \u00e0 l&rsquo;h\u00f4tel<\/h4>\n\n\n\n<p>Pour ceux qui pr\u00e9f\u00e8rent <strong>dormir avec un vrai toit au-dessus de la t\u00eate<\/strong>, vous pouvez opter pour un autre moyen d\u2019h\u00e9bergement. Il y a toujours la possibilit\u00e9 <strong>d\u2019aller \u00e0 l\u2019h\u00f4tel<\/strong>, ce qui \u00e9vite d\u2019avoir \u00e0 planter la tente le soir et permet d\u2019avoir l\u2019esprit un peu plus tranquille. En plus, <strong>\u00e7a all\u00e8ge le chargement<\/strong> car pas besoin d\u2019emporter tout le n\u00e9cessaire de camping. L\u2019inconv\u00e9nient, c\u2019est en revanche d\u2019\u00eatre enferm\u00e9 et de devoir <strong>ressortir de la chambre pour les repas<\/strong>, ce qui n\u2019est pas forc\u00e9ment l\u2019id\u00e9al avec des loulous fatigu\u00e9s de leur journ\u00e9e \u00e0 v\u00e9lo. Sinon, il reste encore <strong>la solution de louer un Airbnb<\/strong>, o\u00f9 l\u00e0 au moins on peut <strong>se cuisiner de bons petits plats<\/strong>.<\/p>\n\n\n\n<h2>Le bivouac en voyage \u00e0 v\u00e9lo<\/h2>\n\n\n\n<p>Si vous \u00eates <strong>fans des nuits sous la tente<\/strong> avec vos loupiots, et que porter (ou tirer) un chargement de plusieurs kilos ne vous fait pas peur, alors <strong>le bivouac pendant votre voyage \u00e0 v\u00e9lo <\/strong>est fait pour vous ! Le gros avantage de ce mode de couchage est <strong>de pouvoir se poser \u00e0 peu pr\u00e8s o\u00f9 on veut<\/strong>, en veillant toujours \u00e0 respecter les endroits autoris\u00e9s. En plus, cela \u00e9vite d&rsquo;avoir un horaire impos\u00e9. Et puis surtout, il y a <strong>un c\u00f4t\u00e9 nature<\/strong> qui ravira toute la famille, car il faudra <strong>d\u00e9nicher le spot parfait o\u00f9 planter la tente<\/strong>. Par contre niveau confort, il n\u2019y aura pas de douches ni de sanitaires comme au camping. Pensez donc \u00e0 <strong>vous poser pr\u00e8s d\u2019un lac ou d\u2019une rivi\u00e8re<\/strong>, si vous voulez faire un brin de toilette.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/bivouac-en-famille-velo.jpg\" alt=\"voyage-velo-en-famille-bivouac\" class=\"wp-image-6628\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/bivouac-en-famille-velo.jpg 1024w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/bivouac-en-famille-velo-300x200.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/bivouac-en-famille-velo-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3>Ce qu&rsquo;il faut savoir<\/h3>\n\n\n\n<p>Il y a tout de m\u00eame certaines choses \u00e0 savoir avant de se lancer. Premi\u00e8rement, <strong>privil\u00e9giez un \u00e9quipement confortable<\/strong>, qui permettra de se reposer efficacement apr\u00e8s une longue journ\u00e9e de p\u00e9dalage. Et si en plus il est <strong>l\u00e9ger et compact<\/strong>, il prendra moins de place dans les sacoches. On fonce donc sur des <strong>matelas et sacs de couchage de qualit\u00e9<\/strong> !&nbsp;<\/p>\n\n\n\n<p>Ensuite, qui dit bivouac, dit forc\u00e9ment, tente ! Le mieux est d\u2019en prendre une <strong>suffisamment grande pour toute la famille<\/strong>, avec assez d\u2019espace <strong>pour y rentrer les sacoches<\/strong> et \u00e9viter de se retrouver vite \u00e0 l\u2019\u00e9troit. Et si en plus on choisit <strong>une tente de randonn\u00e9e l\u00e9g\u00e8re<\/strong>, on gagne quelques kilos non n\u00e9gligeables sur le poids total du chargement.<\/p>\n\n\n\n<p>Comme pour un bivouac en montagne, bien s\u00fbr <strong>on respecte l\u2019environnement qui nous entoure<\/strong>, on ramasse tous nos d\u00e9chets, on efface les traces de feu&#8230;Et on en profite pour montrer tous ces beaux gestes \u00e0 nos loupiots.<\/p>\n\n\n\n<h3>Les repas<\/h3>\n\n\n\n<p>Pour ce qui est des repas, on pr\u00e9voit toujours <strong>de quoi tenir quelques jours<\/strong>, surtout si on sait qu\u2019on ne va rien pouvoir acheter pendant un moment. <strong>C\u00f4t\u00e9 petit d\u00e9j<\/strong>, on ne se prend pas la t\u00eate ! Soit on emm\u00e8ne un peu de lait en poudre pour les oursons, soit on se motive et <strong>on p\u00e9dale jusqu\u2019au prochain caf\u00e9.<\/strong><\/p>\n\n\n\n<p>Et voil\u00e0 ! Vous savez l\u2019essentiel pour <strong>faire du bivouac lors d\u2019un voyage \u00e0 v\u00e9lo en famille<\/strong>. Il n\u2019y a plus qu\u2019\u00e0 trouver le spot parfait o\u00f9 planter la tente ! Et pour \u00eatre s\u00fbr de <strong>bivouaquer dans un endroit r\u00e9glement\u00e9<\/strong>, on s\u2019assure de ne pas \u00eatre sur une propri\u00e9t\u00e9 priv\u00e9e, une zone prot\u00e9g\u00e9e, ou en bord de mer.<\/p>\n\n\n\n<h2>S&rsquo;\u00e9quiper pour une itin\u00e9rance \u00e0 v\u00e9lo avec des enfants<\/h2>\n\n\n\n<p>Maintenant que vous avez choisi votre itin\u00e9raire et vos h\u00e9bergements, vous vous demandez s\u00fbrement <strong>comment vous \u00e9quiper pour un voyage \u00e0 v\u00e9lo en famille.<\/strong><\/p>\n\n\n\n<h3>Faut-il pr\u00e9voir une remorque v\u00e9lo enfant ?<\/h3>\n\n\n\n<p>Tout d\u00e9pendra <strong>de l\u2019\u00e2ge des enfants et de la configuration qu\u2019on a pr\u00e9vu d\u2019adopter<\/strong>. La remorque v\u00e9lo est id\u00e9ale pour emmener vos baroudeurs en herbe pour une randonn\u00e9e \u00e0 v\u00e9lo, jusqu\u2019\u00e0 ce qu\u2019ils soient <strong>en \u00e2ge de p\u00e9daler par eux m\u00eames<\/strong>. Il y a m\u00eame la possibilit\u00e9 d\u2019emmener une draisienne en plus et de l\u2019attacher dessus, si jamais votre bout de chou veut <strong>faire quelques kilom\u00e8tres en autonomie<\/strong>. Le si\u00e8ge v\u00e9lo est une bonne alternative, \u00e0 partir du moment o\u00f9 votre enfant <strong>se tient assis et est capable de maintenir sa t\u00eate<\/strong>. Cependant, la remorque permettra \u00e0 vos loupiots d\u2019\u00eatre <strong>install\u00e9s confortablement pour faire la sieste<\/strong>, mais aussi d\u2019\u00eatre prot\u00e9g\u00e9s en cas d\u2019intemp\u00e9ries, tout en ayant de quoi s\u2019occuper \u00e0 proximit\u00e9. Si vous <strong>voyagez avec un b\u00e9b\u00e9<\/strong>, vous pouvez tout \u00e0 fait <strong>ajouter un hamac<\/strong> sp\u00e9cialement con\u00e7u pour maintenir <strong>de fa\u00e7on ergonomique et confortable votre nourrisson.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/159950663_2896890820633036_4044872652679977276_n.jpg\" alt=\"voyage-velo-en-famille-remorque\" class=\"wp-image-6259\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/159950663_2896890820633036_4044872652679977276_n.jpg 1024w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/159950663_2896890820633036_4044872652679977276_n-300x225.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/04\/159950663_2896890820633036_4044872652679977276_n-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Si vos enfants savent d\u00e9j\u00e0 p\u00e9daler comme des grands, ils pourront avoir leur propre v\u00e9lo, auquel il sera alors possible de <strong>fixer une barre de traction<\/strong>, si jamais ils ne sont pas encore tr\u00e8s \u00e0 l\u2019aise. Ces syst\u00e8mes permettent de <strong>relier votre v\u00e9lo \u00e0 celui de votre loulou<\/strong>, et se mettent en place tr\u00e8s rapidement. Vous pourrez ainsi <strong>alterner les moments en tandem<\/strong>, et ceux o\u00f9 votre loustic p\u00e9dale par lui-m\u00eame. Sachez qu\u2019il existe aussi des v\u00e9los cargos, biporteurs ou triporteurs, ou encore, des tandem. Il y a donc tout plein de solutions pour <strong>emmener votre petite famille p\u00e9daler sur de longues distances !<\/strong><\/p>\n\n\n\n<h3>Bien choisir les v\u00e9los pour toute la famille<\/h3>\n\n\n\n<p>Le <strong>choix du v\u00e9lo<\/strong> est un \u00e9l\u00e9ment important et d\u00e9pendra surtout de <strong>la dur\u00e9e de votre aventure en famille<\/strong>. Le crit\u00e8re le plus important est sans doute d\u2019\u00eatre bien \u00e0 l\u2019aise sur celui-ci, car vous allez <strong>passer un bon nombre d\u2019heures dessus<\/strong>. Il faudra donc veiller \u00e0 ce que chacun ait un v\u00e9lo qui soit bien adapt\u00e9 \u00e0 sa taille. Selon le trajet, o\u00f9 pour \u00eatre tranquille, on peut \u00e9ventuellement <strong>opter pour de la location de v\u00e9los \u00e9lectriques<\/strong>. Attention \u00e9galement \u00e0 toujours bien <strong>v\u00e9rifier l\u2019\u00e9tat de votre bicyclette<\/strong> avant de partir, surtout les pneus et les freins. Privil\u00e9giez du mat\u00e9riel de qualit\u00e9 pour partir l\u2019esprit serein.<\/p>\n\n\n\n<h3>Transporter ses affaires dans les sacoches v\u00e9lo<\/h3>\n\n\n\n<p>Vous vous posez sans doute la question de savoir comment faire pour <strong>transporter tout le mat\u00e9riel n\u00e9cessaire \u00e0 un voyage \u00e0 v\u00e9lo en famille<\/strong> ? Et bien la r\u00e9ponse est simple ! Il existe en effet, des <strong>sacoches de diff\u00e9rents litrages<\/strong>, qui se fixent sur des porte-bagages dispos\u00e9s soit \u00e0 l\u2019avant, soit \u00e0 l\u2019arri\u00e8re du v\u00e9lo, et qui permettent de ranger les affaires. Choisissez-les de pr\u00e9f\u00e9rence <strong>imperm\u00e9ables<\/strong> pour \u00e9viter les mauvaises surprises en cas d\u2019intemp\u00e9ries. Si vous avez une remorque v\u00e9lo, vous pouvez \u00e9galement vous en servir <strong>comme moyen de stockage<\/strong>, surtout si vous devez <strong>transporter du mat\u00e9riel de bivouac.<\/strong><\/p>\n\n\n\n<p>Et on oublie pas, comme pour un bivouac en montagne, <strong>on part l\u00e9ger<\/strong> ! Alors on essaye de <strong>ne pas emmener trop de choses superflues<\/strong>, et au mieux, on teste auparavant sur une petite sortie. Il ne faut pas <strong>surcharger votre bicyclette<\/strong> car cela peut vite devenir lourd \u00e0 porter, sans oublier le poids du v\u00e9lo en lui-m\u00eame. Alors si on ne veut pas \u00eatre charg\u00e9s comme des mules, <strong>on se limite \u00e0 l\u2019essentiel<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/45-ArrivCe-O-Hendaye.jpg\" alt=\"voyage-velo-en-famille-chargement\" class=\"wp-image-5855\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/45-ArrivCe-O-Hendaye.jpg 1024w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/45-ArrivCe-O-Hendaye-300x200.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/45-ArrivCe-O-Hendaye-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Bien charg\u00e9s ! <\/figcaption><\/figure>\n\n\n\n<h2>Concr\u00e8tement, que faut-il emporter pour des vacances \u00e0 v\u00e9lo en famille ? <\/h2>\n\n\n\n<p>Partir l\u00e9ger ne veut pas dire partir avec rien : le tout est <strong>d\u2019emporter le n\u00e9cessaire pour votre aventure<\/strong>. Voil\u00e0 une checklist rapide des choses les plus importantes \u00e0 ne pas oublier :<\/p>\n\n\n\n<h3>C\u00f4t\u00e9 v\u00eatements<\/h3>\n\n\n\n<ul><li>Des v\u00eatements chauds, imperm\u00e9ables, quelques t-shirts et shorts ou pantalons de rechange, un coupe-vent, un maillot de bain, une casquette, des gants de v\u00e9lo et des baskets. Le tout <strong>rang\u00e9 dans des sacs zipp\u00e9s comme pour le bivouac<\/strong>. Le mieux est de privil\u00e9gier <strong>des v\u00eatements confortables<\/strong> pour rouler et des chaussures adapt\u00e9es.<\/li><li>On oublie pas les <strong>lunettes de soleil et la cr\u00e8me solaire<\/strong><\/li><\/ul>\n\n\n\n<h3>C\u00f4t\u00e9 repas<\/h3>\n\n\n\n<ul><li>De la <strong>nourriture de base pour quelques jours d\u2019autonomie<\/strong>, tout en pr\u00e9voyant beaucoup de snacks selon ce qu\u2019aiment les enfants, c\u2019est primordial !&nbsp;<\/li><\/ul>\n\n\n\n<h3>Pour le camping<\/h3>\n\n\n\n<ul><li>Si on fait du camping, il est indispensable d\u2019avoir les classiques : <strong>une tente<\/strong>, l\u00e9g\u00e8re et facile \u00e0 monter de pr\u00e9f\u00e9rence ; des <strong>sacs de couchage assez chauds et des tapis de sol<\/strong> ; une popote et de la vaisselle de base.&nbsp;<\/li><\/ul>\n\n\n\n<h3>Les indispensables<\/h3>\n\n\n\n<ul><li>Du <strong>mat\u00e9riel de r\u00e9paration v\u00e9lo<\/strong> : des chambres \u00e0 air, de la rustine, de la colle, un outil multifonction, du ruban adh\u00e9sif.<\/li><li>Des <strong>casques<\/strong> (on oublie pas que le port du casque est obligatoire pour les enfants de moins de 12 ans), des gilets jaunes, des antivols pour les arr\u00eats en ville.<\/li><li>Divers : une rallonge et une multiprise, du papier toilette, des sacs poubelle et \u00e9tanches, quelques jeux pour les marmots, une corde pour \u00e9tendre le linge, un peu de lessive, une lampe frontale pour la nuit, une b\u00e2che pour prot\u00e9ger les v\u00e9los en cas d\u2019intemp\u00e9ries ou pour mettre sur la tente.<\/li><li>Si on <strong>voyage avec un b\u00e9b\u00e9<\/strong> : il faudra pr\u00e9voir des couches, lavables ou jetables selon la dur\u00e9e du voyage, mais aussi du lait en poudre et toutes les affaires n\u00e9cessaires \u00e0 votre nourrisson.<\/li><\/ul>\n\n\n\n<p>N\u2019oubliez pas non plus <strong>d\u2019emporter un topo guide ou de t\u00e9l\u00e9charger les traces de votre parcours<\/strong> sur un smartphone ou un GPS v\u00e9lo.<\/p>\n\n\n\n<h2>Rejoindre le point de d\u00e9part de l&rsquo;itin\u00e9raire<\/h2>\n\n\n\n<p>Maintenant que toute la famille est \u00e9quip\u00e9e, il va falloir <strong>rejoindre le point de d\u00e9part de votre voyage \u00e0 v\u00e9lo en famille.<\/strong><\/p>\n\n\n\n<h3>Transporter son \u00e9quipement de v\u00e9lo dans le train<\/h3>\n\n\n\n<p><strong>Rejoindre le point de d\u00e9part de son aventure en train<\/strong> est une solution pratique et \u00e9cologique. Mais cela peut aussi s\u2019av\u00e9rer \u00eatre un peu un parcours du combattant. Il y a en effet <strong>quelques sp\u00e9cificit\u00e9s<\/strong> \u00e0 conna\u00eetre avant de se lancer. Tout d\u2019abord, vous verrez que certaines gares sont \u00e0 peu pr\u00e8s am\u00e9nag\u00e9es, mais pas les plus petites o\u00f9 vous devrez <strong>porter tout votre \u00e9quipement dans les escaliers.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/46-Retour-en-train-avec-tout-notre-chargement.jpg\" alt=\"voyage-velo-en-famille-train\" class=\"wp-image-5860\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/46-Retour-en-train-avec-tout-notre-chargement.jpg 1024w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/46-Retour-en-train-avec-tout-notre-chargement-300x225.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/03\/46-Retour-en-train-avec-tout-notre-chargement-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Prendre le train avec tout l&rsquo;\u00e9quipement, c&rsquo;est possible !<\/figcaption><\/figure>\n\n\n\n<p>Ensuite, les v\u00e9los <strong>d\u00e9mont\u00e9s et pli\u00e9s dans des housses<\/strong> sont accept\u00e9s dans tous les trains.  Mais attention, s\u2019amuser \u00e0 d\u00e9monter des v\u00e9los est <strong>une solution peu pratique<\/strong> car on se retrouve \u00e0 ne pas savoir quoi faire des housses une fois arriv\u00e9s sur place. Pour les <strong>v\u00e9los non d\u00e9mont\u00e9s<\/strong>, c\u2019est un peu moins compliqu\u00e9. Une fois le train arriv\u00e9 en gare, il suffit de <strong>rep\u00e9rer le wagon qui comporte un pictogramme<\/strong> et d\u2019embarquer rapidement \u00e0 bord de celui-ci. Une fois \u00e0 l\u2019int\u00e9rieur, vous pourrez <strong>placer les v\u00e9los sur des crochets d\u00e9di\u00e9s<\/strong>, si ceux-ci sont libres. En g\u00e9n\u00e9ral, ce dispositif est <strong>gratuit et sans r\u00e9servation dans les TER<\/strong>, et payant dans les quelques TGV qui acceptent les v\u00e9los d\u00e9mont\u00e9s. Si jamais il n\u2019y a pas de crochets libres, il faut se d\u00e9brouiller pour ranger les v\u00e9los ailleurs dans le wagon.<\/p>\n\n\n\n<p>En bref, <strong>prendre le train pour rejoindre le point de d\u00e9part de son itin\u00e9raire<\/strong> est une bonne solution, si on privil\u00e9gie les horaires o\u00f9 il n\u2019y a pas trop de monde et si on oublie les correspondances !<\/p>\n\n\n\n<h3>Y aller en voiture<\/h3>\n\n\n\n<p>Une autre solution pour aller au d\u00e9part de votre <strong>voyage \u00e0 v\u00e9lo en famille <\/strong>est de prendre la voiture. Evidemment, c\u2019est bien plus pratique mais aussi moins \u00e9cologique. Ce moyen de transport sera \u00e0 privil\u00e9gier si on a <strong>plusieurs correspondances \u00e0 effectuer<\/strong> et qu\u2019on ne veut pas s\u2019emb\u00eater avec le train. Dans ces cas-l\u00e0, plusieurs solutions sont possibles :<\/p>\n\n\n\n<ul><li><strong>Opter pour un itin\u00e9raire en boucle<\/strong>, qui revient au point de d\u00e9part<\/li><li><strong>Prendre une navette ou un train au retour<\/strong><\/li><li>Utiliser les services d\u2019un transporteur priv\u00e9 pour les v\u00e9los et bagages<\/li><\/ul>\n\n\n\n<p>Il faudra aussi <strong>trouver un parking<\/strong> pour y laisser la voiture pendant la dur\u00e9e de votre p\u00e9riple.<\/p>\n\n\n\n<h2>Quelques derniers conseils avant de se mettre en selle en famille<\/h2>\n\n\n\n<p>Pour profiter pleinement de votre <strong>voyage \u00e0 v\u00e9lo en famille<\/strong>, voici nos quelques derniers conseils :<\/p>\n\n\n\n<ul><li><strong>Suivez le rythme de vos enfants <\/strong>et tout se passera bien ! Ils prendront vite leur marques et d\u00e9velopperont leurs propres habitudes. Et puis, l\u2019essentiel est que vous partagiez cette aventure ensemble et que vous reveniez avec des souvenirs inoubliables.&nbsp;<\/li><li><strong>Soyez pr\u00e9par\u00e9s pour faire face \u00e0 l\u2019impr\u00e9vu<\/strong> ! Mais bon, c\u2019est aussi \u00e7a l\u2019aventure, non ?<\/li><li>Allez <strong>\u00e0 votre propre rythme<\/strong> et ne surestimez pas vos capacit\u00e9s, ni celles de vos loupiots.<\/li><li>Ne pas oublier que le code de la route s\u2019applique lorsqu\u2019on circule \u00e0 v\u00e9lo. N\u2019h\u00e9sitez pas \u00e0 donner aux enfants les <strong>r\u00e8gles essentielles de s\u00e9curit\u00e9<\/strong> avant chaque balade, surtout s&rsquo;ils ont leur propre v\u00e9lo.<\/li><\/ul>\n\n\n\n<p>Et voil\u00e0, vous \u00eates d\u00e9sormais fins pr\u00eats pour votre <strong>voyage \u00e0 v\u00e9lo en famille !<\/strong><\/p>\n\n\n\n<h2>HEY, SI ON \u00c9QUIPAIT VOS PETITS BAROUDEURS ?<\/h2>\n\n\n\n<p>Chez les Petits Baroudeurs, nous&nbsp;<strong>d\u00e9nichons avec soin et amour<\/strong>&nbsp;les produits utiles \u00e0 vos aventures en famille.&nbsp;<strong>Nous les testons<\/strong>&nbsp;avec nos Oursons, les cousins, les amis de nos loupiots \u2013 quand nos enfants sont trop grands pour tester eux m\u00eame. Et&nbsp;<strong>nous ne s\u00e9lectionnons que les meilleurs produits&nbsp;<\/strong>pour vous les proposer.<\/p>\n\n\n\n<p>Voici donc la s\u00e9lection de notre boutique pour partir faire une itin\u00e9rance \u00e0 v\u00e9lo en famille :<\/p>\n\n\n\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns alignwide\">\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/velo-et-vtt-enfant-93\"><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/puky-s-pro-20-velo-20-moins-de-6-kg-300-300.jpg\" alt=\"\" class=\"wp-image-6654\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/puky-s-pro-20-velo-20-moins-de-6-kg-300-300.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/puky-s-pro-20-velo-20-moins-de-6-kg-300-300-150x150.jpg 150w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/puky-s-pro-20-velo-20-moins-de-6-kg-300-300-270x270.jpg 270w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption><em>V\u00e9lo enfant<br><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/velo-et-vtt-enfant-93\" target=\"_blank\" rel=\"noreferrer noopener\">Je d\u00e9couvre<\/a><\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-buttons\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/remorque-velo-enfant-80\"><img loading=\"lazy\" width=\"800\" height=\"800\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300.jpg\" alt=\"\" class=\"wp-image-6655\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300.jpg 800w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300-300x300.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300-150x150.jpg 150w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300-768x768.jpg 768w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300-270x270.jpg 270w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300-540x540.jpg 540w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/thule-chariot-cross-300-300-580x580.jpg 580w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption><em>Remorque v\u00e9lo enfant<br><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/remorque-velo-enfant-80\" target=\"_blank\" rel=\"noreferrer noopener\">Je d\u00e9couvre<\/a><\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-buttons\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/porte-bagages-et-sacoches-266\"><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/sacoches-velo-shield-pannier-13l-ou-25l-thule-300-300.jpg\" alt=\"\" class=\"wp-image-6656\" srcset=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/sacoches-velo-shield-pannier-13l-ou-25l-thule-300-300.jpg 300w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/sacoches-velo-shield-pannier-13l-ou-25l-thule-300-300-150x150.jpg 150w, https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/sacoches-velo-shield-pannier-13l-ou-25l-thule-300-300-270x270.jpg 270w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption><em>Sacoches v\u00e9lo<br><a href=\"https:\/\/www.lespetitsbaroudeurs.com\/porte-bagages-et-sacoches-266\" target=\"_blank\" rel=\"noreferrer noopener\">Je d\u00e9couvre<\/a><\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-buttons\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez envie de vous lancer dans un premier voyage \u00e0 v\u00e9lo en famille mais vous vous posez encore mille et une questions ? D\u00e9couvrez tous nos conseils pour pr\u00e9parer au mieux votre voyage et partez p\u00e9daler avec vos enfants ! Organiser son voyage \u00e0 v\u00e9lo en famille Avant toute chose, il faut savoir qu\u2019il [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":6664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[136],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pr\u00e9parer un voyage \u00e0 v\u00e9lo en famille : nos conseils<\/title>\n<meta name=\"description\" content=\"De la pr\u00e9paration de l&#039;itin\u00e9raire, au choix de l&#039;\u00e9quipement, d\u00e9couvrez tous nos conseils pour pr\u00e9parer votre voyage \u00e0 v\u00e9lo en famille !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9parer un voyage \u00e0 v\u00e9lo en famille : nos conseils\" \/>\n<meta property=\"og:description\" content=\"De la pr\u00e9paration de l&#039;itin\u00e9raire, au choix de l&#039;\u00e9quipement, d\u00e9couvrez tous nos conseils pour pr\u00e9parer votre voyage \u00e0 v\u00e9lo en famille !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Petits Baroudeurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lespetitsbaroudeurs\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T09:46:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T08:04:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/header-velo-en-famille.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1136\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#website\",\"url\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/\",\"name\":\"Les Petits Baroudeurs\",\"description\":\"Le Blog de l&#039;aventure en famille !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-content\/uploads\/2021\/06\/header-velo-en-famille.png\",\"width\":1136,\"height\":530},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/#webpage\",\"url\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/\",\"name\":\"Pr\\u00e9parer un voyage \\u00e0 v\\u00e9lo en famille : nos conseils\",\"isPartOf\":{\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/#primaryimage\"},\"author\":{\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#\/schema\/person\/074061ec8b5473878afb9cce3c002d69\"},\"description\":\"De la pr\\u00e9paration de l'itin\\u00e9raire, au choix de l'\\u00e9quipement, d\\u00e9couvrez tous nos conseils pour pr\\u00e9parer votre voyage \\u00e0 v\\u00e9lo en famille !\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/nos-conseils-pour-preparer-un-voyage-a-velo-en-famille\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#\/schema\/person\/074061ec8b5473878afb9cce3c002d69\",\"name\":\"C\\u00e9line Lacombe\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.lespetitsbaroudeurs.com\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3196c6923379068e921575c340f8486?s=96&d=mm&r=g\",\"caption\":\"C\\u00e9line Lacombe\"},\"description\":\"Amoureuse des montagnes et des voyages, C\\u00e9line est heureuse dans sa tribu familiale avec ses mini baroudeurs et son homme. La cr\\u00e9ation des Petits Baroudeurs est la suite logique de sa passion pour sa famille et pour l'outdoor.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts\/6636"}],"collection":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/comments?post=6636"}],"version-history":[{"count":21,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts\/6636\/revisions"}],"predecessor-version":[{"id":6666,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/posts\/6636\/revisions\/6666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/media\/6664"}],"wp:attachment":[{"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/media?parent=6636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/categories?post=6636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lespetitsbaroudeurs.com\/blog\/wp-json\/wp\/v2\/tags?post=6636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}